{"id":1280,"date":"2023-09-25T12:21:43","date_gmt":"2023-09-25T04:21:43","guid":{"rendered":"http:\/\/ly.yishihui.net\/meng\/?p=1280"},"modified":"2023-09-25T11:15:09","modified_gmt":"2023-09-25T03:15:09","slug":"%e5%bf%83%e7%90%86%e5%ad%a6%e8%a7%a3%e6%a2%a6%e6%a2%a6%e8%a7%81%e4%b8%a4%e6%80%a7%e4%ba%ba%e6%98%af%e4%bb%80%e4%b9%88%e5%af%93%e6%84%8f%ef%bc%9f%e6%a2%a6%e8%a7%81%e5%be%88%e5%a4%9a%e4%b8%a4%e6%80%a7","status":"publish","type":"post","link":"http:\/\/ms.yishihui.net\/meng\/1280.htm","title":{"rendered":"\u5fc3\u7406\u5b66\u89e3\u68a6\u68a6\u89c1\u4e24\u6027\u4eba\u662f\u4ec0\u4e48\u5bd3\u610f\uff1f\u68a6\u89c1\u5f88\u591a\u4e24\u6027\u4eba\u597d\u4e0d\u597d\uff1f"},"content":{"rendered":"<p>\u505a\u68a6\u68a6\u89c1\u4e24\u6027\u4eba\u65e2\u6709\u505a\u68a6\u8005\u73b0\u5b9e\u7684\u5f71\u54cd\u548c\u53cd\u5e94\uff0c\u4e5f\u6709\u68a6\u8005\u7684\u4e3b\u89c2\u6f5c\u610f\u8bc6\u60f3\u8c61\uff0c\u505a\u68a6\u68a6\u89c1\u4e24\u6027\u4eba\u662f\u4ec0\u4e48\u610f\u601d\uff1f\u5468\u516c\u89e3\u68a6\u68a6\u89c1\u4e24\u6027\u4eba\u610f\u5473\u7740\u4ec0\u4e48\uff1f\u68a6\u5230\u4e24\u6027\u4eba\u9884\u793a\u7740\u4ec0\u4e48\uff1f\u597d\u4e0d\u597d\uff1f\u8bf7\u770b\u4e0b\u9762\u7531\u6613\u5e08\u6c47\u89e3\u68a6\u680f\u76ee\u5c0f\u7f16\u5e2e\u4f60\u6574\u7406\u7684\u68a6\u89c1\u4e24\u6027\u4eba\u7684\u8be6\u7ec6\u89e3\u8bf4\u3002<\/p>\n<p><b>\u68a6\u89c1\u4e24\u6027\u4eba\u662f\u4ec0\u4e48\u610f\u601d\u5468\u516c\u89e3\u68a6\uff1f\u68a6\u89c1\u81ea\u5df1\u53d8\u6210\u4e24\u6027\u4eba\u9884\u793a\u4ec0\u4e48\uff1f<\/b><\/p>\n<p>\u68a6\u89c1\u81ea\u5df1\u53d8\u6210\u4e24\u6027\u4eba\uff0c\u6709\u53ef\u80fd\u4f1a\u906d\u53d7\u635f\u5931\u3002<\/p>\n<p>\u68a6\u89c1\u4e24\u6027\u4eba\u6216\u96cc\u96c4\u540c\u4f53\u7684\u751f\u7269\uff0c\u8868\u793a\u4f60\u5bf9\u81ea\u5df1\u7684\u6027\u522b\u89d2\u8272\u5b58\u5728\u7591\u95ee\u6216\u8005\u4e0d\u6ee1\u610f\u3002<\/p>\n<p>\u8001\u4eba\u68a6\u89c1\u81ea\u5df1\u53d8\u6210\u4e24\u6027\u4eba\uff0c\u4e3b\u8fd1\u671f\u8fd0\u52bf\u9010\u6e10\u8f6c\u4e3a\u987a\u5229\uff0c\u4f46\u4e0d\u53ef\u64cd\u4e4b\u8fc7\u6025\uff0c\u4e00\u5b9a\u8981\u5faa\u5e8f\u6e10\u8fdb\u3002<\/p>\n<p>\u68a6\u89c1\u4f60\u81ea\u5df1\u6216\u662f\u4ed6\u4eba\u662f\u4e00\u4e2a\u4e24\u6027\u4eba\uff0c\u90fd\u8bf4\u660e\u4f60\u5e94\u8be5\u5bf9\u4f60\u5962\u4f88\u3001\u653e\u8361\u7684\u751f\u6d3b\u8981\u6709\u6240\u6536\u655b\uff0c\u5982\u82e5\u4e0d\u77e5\u6094\u6539\uff0c\u5c06\u4f1a\u81ea\u98df\u82e6\u679c\u3002<\/p>\n<p>\u5973\u4eba\u68a6\u89c1\u81ea\u5df1\u6210\u4e3a\u53cc\u6027\u4eba\u65f6\u4e0e\u5973\u4eba\u4ea4\u6b22\uff0c\u662f\u4ee5\u5bf9\u73b0\u5b9e\u751f\u6d3b\u7684\u4e0d\u6ee1\uff0c\u7ecf\u5e38\u4f1a\u6028\u5929\u5c24\u4eba\uff0c\u4e0e\u90bb\u5c45\u5435\u67b6\u5728\u6240\u96be\u514d;\u4f46\u662f\u68a6\u89c1\u4e0e\u7537\u4eba\u4ea4\u6b22\uff0c\u5219\u662f\u5409\u5146\uff0c\u751f\u6d3b\u5bb6\u5ead\u7231\u60c5\u90fd\u4f1a\u4f7f\u4f60\u79f0\u5fc3\u6ee1\u610f\uff0c\u6bcf\u5929\u90fd\u5904\u5728\u5174\u594b\u4e4b\u4e2d\u3002<\/p>\n<p>\u7537\u4eba\u68a6\u89c1\u81ea\u5df1\u6210\u4e3a\u53cc\u6027\u4eba\u65f6\u4e0e\u5973\u4eba\u4ea4\u6b22\uff0c\u81ea\u7531\u5219\u662f\u4e2a\u5178\u578b\u7684\u82b1\u82b1\u516c\u5b50\u578b\uff0c\u81ea\u4fe1\u8fc7\u5934\u4fbf\u662f\u81ea\u8d1f\uff0c\u6700\u540e\u6ca6\u843d\u4e3a\u5b64\u5bb6\u5be1\u4eba\u5728\u6240\u96be\u514d\u54e6;\u4f46\u662f\u68a6\u89c1\u4e0e\u7537(\u7cfb\u7edf:\u7231\u62a4\u8054\u76df\u73af\u5883\u8bf7\u4f7f\u7528\u6587\u660e\u7528\u8bed)\u6b22\uff0c\u81ea\u5df1\u4f1a\u56e0\u8fc7\u4e8e\u4fdd\u5b88\u800c\u675f\u624b\u675f\u811a\uff0c\u9519\u5931\u4e86\u5f88\u591a\u826f\u673a\uff0c\u4e00\u751f\u4e5f\u53ea\u662f\u4e2a\u5e73\u5eb8\u4e4b\u8f88\u3002<\/p>\n<p>\u68a6\u89c1\u6709\u5f88\u591a\u53cc\u6027\u4eba\uff0c\u5219\u4e0d\u662f\u7965\u4e4b\u5146\uff0c\u5c45\u4f4f\u5730\u4f1a\u81ea\u7136\u707e\u5bb3\u53d1\u751f\uff0c\u5e94\u5c3d\u65e9\u63d0\u9632\u3002<\/p>\n<p><b>\u5fc3\u7406\u5b66\u89e3\u68a6\u68a6\u89c1\u4e24\u6027\u4eba\u662f\u4ec0\u4e48\u5bd3\u610f\uff1f<\/b><\/p>\n<p>1\u3001\u68a6\u5883\u89e3\u8bf4\uff1a\u68a6\u89c1\u4e24\u6027\u4eba\u6216\u96cc\u96c4\u540c\u4f53\u7684\u751f\u7269\u8868\u793a\u4f60\u5bf9\u81ea\u5df1\u7684\u6027\u522b\u89d2\u8272\u5b58\u5728\u7591\u95ee\u6216\u8005\u4e0d\u6ee1\u610f\u3002\u6b64\u5916\uff0c\u5982\u679c\u4f60\u5e0c\u671b\u5bf9\u672c\u8eab\u6709\u8fdb\u4e00\u6b65\u7684\u4e86\u89e3\uff0c\u4f60\u5c31\u5fc5\u987b\u52aa\u529b\u5728\u81ea\u5df1\u7406\u6027\u7684\u4e00\u9762\u548c\u611f\u60c5\u7684\u4e00\u9762\u4f5c\u51fa\u5e73\u8861\uff0c\u800c\u8fd9\u79cd\u5fc3\u7406\u72b6\u6001\u4f1a\u5728\u4f60\u7684\u68a6\u4e2d\u4ee5\u4e24\u6027\u4eba\u7684\u5f62\u5f0f\u8868\u73b0\u51fa\u73b0\u3002<\/p>\n<p>2\u3001\u5fc3\u7406\u5206\u6790\uff1a\u5b69\u5b50\u5728\u6210\u957f\u8fc7\u7a0b\u4e2d\u4f1a\u9010\u6e10\u61c2\u5f97\uff0c\u6709\u4e9b\u884c\u4e3a\u662f\u5408\u4e4e\u60c5\u7406\u800c\u80fd\u88ab\u63a5\u53d7\uff0c\u800c\u6709\u4e9b\u5219\u4e0d\u80fd\u3002\u8fd9\u5c31\u5bfc\u81f4\u4ed6\u4eec\u5728\u4eba\u6027\u4e2d\u4e00\u90e8\u5206\u53d7\u5230\u538b\u6291\u800c\u5728\u540e\u6765\u7684\u65e5\u5b50\u91cc\u624d\u80fd\u5f97\u4ee5\u91ca\u653e\u51fa\u6765\u3002\u7c7b\u4f3c\u7684\u95ee\u9898\u4f1a\u4f7f\u4eba\u4eec\u7591\u60d1\u4e0d\u5b89\uff0c\u4e8e\u662f\u5728\u68a6\u4e2d\u5c31\u4ee5\u4e24\u6027\u4eba\u7684\u5177\u4f53\u5f62\u5f0f\u8868\u73b0\u51fa\u6765\u3002<\/p>\n<p>\u7cbe\u795e\u8c61\u5f81\uff1a\u68a6\u4e2d\u51fa\u73b0\u7684\u4e24\u6027\u4eba\u8868\u793a\u4e00\u79cd\u5b8c\u5168\u7684\u5e73\u8861\u3002<\/p>\n<p>\u4ee5\u4e0a\u5c31\u662f\u7531\u6613\u5e08\u6c47\u89e3\u68a6\u680f\u76ee\u5c0f\u7f16\u5e2e\u4f60\u6574\u7406\u7684\u5173\u4e8e\u5468\u516c\u89e3\u68a6\u68a6\u89c1\u4e24\u6027\u4eba\u662f\u4ec0\u4e48\u5f81\u5146\uff1f\u68a6\u5230\u4e24\u6027\u4eba\u662f\u4ec0\u4e48\u5bd3\u610f\uff1f\u597d\u4e0d\u597d\u65b9\u9762\u7684\u5185\u5bb9\u3002\u5e0c\u671b\u5bf9\u5927\u5bb6\u6709\u6240\u5e2e\u52a9\u3002\u66f4\u591a\u89e3\u68a6\u53ef\u4ee5\u7ad9\u5185\u641c\u7d22\u5173\u952e\u8bcd\u5373\u53ef\u3002\uff01<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u505a\u68a6\u68a6\u89c1\u4e24\u6027\u4eba\u65e2\u6709\u505a\u68a6\u8005\u73b0\u5b9e\u7684\u5f71\u54cd\u548c\u53cd\u5e94\uff0c\u4e5f\u6709\u68a6\u8005\u7684\u4e3b\u89c2\u6f5c\u610f\u8bc6\u60f3\u8c61\uff0c\u505a\u68a6\u68a6\u89c1\u4e24\u6027\u4eba\u662f\u4ec0\u4e48\u610f\u601d\uff1f\u5468\u516c\u89e3\u68a6\u68a6\u89c1\u4e24\u6027\u4eba\u610f\u5473\u7740\u4ec0\u4e48\uff1f\u68a6\u5230\u4e24\u6027\u4eba\u9884\u793a\u7740\u4ec0\u4e48\uff1f\u597d\u4e0d\u597d\uff1f\u8bf7\u770b\u4e0b\u9762\u7531\u6613\u5e08\u6c47\u89e3\u68a6\u680f\u76ee\u5c0f\u7f16\u5e2e\u4f60\u6574\u7406\u7684\u68a6\u89c1\u4e24\u6027\u4eba\u7684\u8be6\u7ec6\u89e3\u8bf4\u3002 \u68a6\u89c1\u4e24\u6027\u4eba\u662f\u4ec0\u4e48\u610f\u601d\u5468\u516c\u89e3\u68a6\uff1f\u68a6\u89c1\u81ea\u5df1\u53d8\u6210\u4e24\u6027\u4eba\u9884\u793a\u4ec0\u4e48\uff1f \u68a6\u89c1\u81ea\u5df1\u53d8\u6210\u4e24\u6027\u4eba\uff0c\u6709\u53ef\u80fd\u4f1a\u906d\u53d7\u635f\u5931\u3002 \u68a6\u89c1\u4e24\u6027\u4eba\u6216\u96cc\u96c4\u540c\u4f53\u7684\u751f\u7269\uff0c\u8868\u793a\u4f60\u5bf9\u81ea\u5df1\u7684\u6027&hellip; <a href=\"http:\/\/ms.yishihui.net\/meng\/1280.htm\" class=\"more-link read-more\" rel=\"bookmark\">\u7ee7\u7eed\u9605\u8bfb <span class=\"screen-reader-text\">\u5fc3\u7406\u5b66\u89e3\u68a6\u68a6\u89c1\u4e24\u6027\u4eba\u662f\u4ec0\u4e48\u5bd3\u610f\uff1f\u68a6\u89c1\u5f88\u591a\u4e24\u6027\u4eba\u597d\u4e0d\u597d\uff1f<\/span><i class=\"fa fa-arrow-right\"><\/i><\/a><\/p>\n","protected":false},"author":1,"featured_media":6461,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[7,2262,5,6],"class_list":{"0":"post-1280","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-cw","8":"tag-7","9":"tag-2262","10":"tag-5","11":"tag-6","12":"h-entry","14":"h-as-article"},"_links":{"self":[{"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/posts\/1280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/comments?post=1280"}],"version-history":[{"count":2,"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/posts\/1280\/revisions"}],"predecessor-version":[{"id":9622,"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/posts\/1280\/revisions\/9622"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/media\/6461"}],"wp:attachment":[{"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/media?parent=1280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/categories?post=1280"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/tags?post=1280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}