{"id":5150,"date":"2023-07-14T09:24:50","date_gmt":"2023-07-14T01:24:50","guid":{"rendered":"http:\/\/ly.yishihui.net\/meng\/?p=5150"},"modified":"2023-07-14T09:36:03","modified_gmt":"2023-07-14T01:36:03","slug":"%e6%a2%a6%e8%a7%81%e6%b5%b8%e5%9c%a8%e6%b0%b4%e4%b8%ad%e4%bb%80%e4%b9%88%e5%af%93%e6%84%8f%e5%91%a8%e5%85%ac%e8%a7%a3%e6%a2%a6%ef%bc%9f%e6%a2%a6%e8%a7%81%e4%be%b5%e5%85%a5%e6%b0%b4%e4%b8%ad%e5%a5%bd","status":"publish","type":"post","link":"http:\/\/ms.yishihui.net\/meng\/5150.htm","title":{"rendered":"\u68a6\u89c1\u6d78\u5728\u6c34\u4e2d\u4ec0\u4e48\u5bd3\u610f\u5468\u516c\u89e3\u68a6\uff1f\u68a6\u89c1\u4fb5\u5165\u6c34\u4e2d\u597d\u5417\uff1f"},"content":{"rendered":"<p>\u68a6\u91cc\u68a6\u5230\u6d78\u5728\u6c34\u4e2d\u662f\u4ec0\u4e48\u5f81\u5146\uff1f\u5468\u516c\u89e3\u68a6\u68a6\u89c1\u6d78\u5728\u6c34\u4e2d\u662f\u4ec0\u4e48\u610f\u601d\uff1f\u68a6\u5230\u6d78\u5728\u6c34\u4e2d\u9884\u793a\u7740\u4ec0\u4e48\uff1f\u597d\u4e0d\u597d\uff1f\u505a\u68a6\u68a6\u89c1\u6d78\u5728\u6c34\u4e2d\u6709\u4ec0\u4e48\u5bd3\u610f?\u5f88\u591a\u4eba\u90fd\u6709\u8fd9\u65b9\u9762\u7684\u89e3\u68a6\u7591\u8651\u3002\u4eca\u5929\u6613\u5e08\u6c47\u89e3\u68a6\u680f\u76ee\u5c0f\u7f16\u5e2e\u4f60\u6574\u7406\u7684\u68a6\u89c1\u6d78\u5728\u6c34\u4e2d\u7684\u8be6\u7ec6\u89e3\u8bf4\u3002<\/p>\n<p><b>\u68a6\u89c1\u6d78\u5728\u6c34\u4e2d\u662f\u4ec0\u4e48\u5bd3\u610f\u5468\u516c\u89e3\u68a6\uff1f\u68a6\u89c1\u4fb5\u5728\u6c34\u4e2d\u597d\u4e0d\u597d\uff1f<\/b><\/p>\n<p>\u68a6\u5230\u81ea\u5df1\u88ab\u6d78\u5165\u6c34\u4e2d\uff0c\u4e00\u822c\u8868\u793a\u68a6\u8005\u5904\u7406\u611f\u60c5\u7684\u72b6\u51b5\u3002\u4ed6\u8bd5\u7740\u5bfb\u627e\u6027\u683c\u4e2d\u7edd\u4e0d\u80fd\u88ab\u5916\u754c\u73af\u5883\u5f71\u54cd\u7684\u65e0\u8f9c\u7684\u90e8\u5206\u3002\u4ed6\u52aa\u529b\u4f7f\u5f62\u52bf\u660e\u6717\uff0c\u5e76\u6e05\u6d01\u81ea\u5df1&#8211;\u4e5f\u8bb8\u662f\u6e05\u9664\u90a3\u4e9b\u522b\u4eba\u585e\u7ed9\u4ed6\u7684\u89c2\u70b9\u548c\u60f3\u6cd5\u3002<\/p>\n<p><span style=\"font-size: medium;\">\u6253\u7b97\u51fa\u95e8\u7684\u4eba\u68a6\u89c1\u6d78\u5728\u6c34\u4e2d\uff0c\u5efa\u8bae\u987a\u5229\u5e73\u5b89\uff0c\u590f\u5360\u4e0d\u5229\u3002<\/span><\/p>\n<p><span style=\"font-size: medium;\">\u51c6\u5907\u8003\u8bd5\u7684\u4eba\u68a6\u89c1\u6d78\u5728\u6c34\u4e2d\uff0c\u610f\u5473\u7740\u4e0d\u80fd\u4e13\u5fc3\u5e94\u8003\uff0c\u5f55\u53d6\u673a\u4f1a\u4e0d\u5927\u3002<\/span><\/p>\n<p><span style=\"font-size: medium;\">\u6000\u6709\u8eab\u5b55\u7684\u4eba\u68a6\u89c1\u6d78\u5728\u6c34\u4e2d\uff0c\u9884\u793a\u751f\u5973\uff0c\u51ac\u5360\u751f\u7537\uff0c\u6ce8\u610f\u996e\u98df\u8282\u5236\u3002<\/span><\/p>\n<p><span style=\"font-size: medium;\">\u521b\u4e1a\u7684\u4eba\u68a6\u89c1\u6d78\u5728\u6c34\u4e2d\uff0c\u4ee3\u8868\u8fc7\u521a\u6709\u788d\u4e8b\u4e1a\u8d22\u5229\uff0c\u5b9c\u591a\u53cd\u7701\uff0c\u5f97\u4eba\u548c\u4e3a\u8981\u3002<\/span><\/p>\n<p><span style=\"font-size: medium;\">\u8c08\u5a5a\u8bba\u5ac1\u7684\u4eba\u68a6\u89c1\u6d78\u5728\u6c34\u4e2d\uff0c\u8bf4\u660e\u5e74\u7eaa\u76f8\u5dee\u5927\u4e9b\uff0c\u597d\u597d\u57f9\u517b\u611f\u60c5\u5a5a\u59fb\u53ef\u6210\u3002<\/span><\/p>\n<p><span style=\"font-size: medium;\">\u68a6\u89c1\u522b\u4eba\u6d78\u5728\u6c34\u4e2d\uff0c\u901a\u5e38\u8868\u793a\u5bf9\u611f\u60c5\u7684\u6e34\u6c42\uff0c\u6216\u5bf9\u6027\u6b32\u7684\u6e34\u671b\u3002<\/span><\/p>\n<p><span style=\"font-size: medium;\">\u68a6\u89c1\u81ea\u5df1\u5728\u6c34\u4e2d\u6d78\u7740\uff0c\u8bf4\u660e\u4f60\u5185\u5fc3\u6df1\u5904\u6bd4\u8f83\u70e6\u4e71\uff0c\u6216\u662f\u751f\u6d3b\u4e2d\u6709\u4e9b\u4e8b\u60c5\u8ba9\u4f60\u611f\u5230\u6709\u538b\u529b\uff0c\u4f60\u60f3\u8981\u4ece\u8fd9\u4e9b\u70e6\u4e71\u7684\u60c5\u7eea\u4e2d\u9003\u79bb\u51fa\u6765\u3002<\/span><\/p>\n<p><span style=\"font-size: medium;\">\u604b\u7231\u4e2d\u7684\u4eba\u68a6\u89c1\u522b\u4eba\u6d78\u5728\u6c34\u4e2d\uff0c\u8bf4\u660e\u638c\u63e1\u65f6\u673a\u6c42\u5a5a\u5fc5\u6709\u7ed3\u679c\uff0c\u5a5a\u59fb\u53ef\u6210\u3002<\/span><\/p>\n<p>\u5982\u679c\u68a6\u8005\u5728\u68a6\u91cc\u5b8c\u5168\u88ab\u6d78\u6ca1(\u8fd9\u662f\u6307\u5168\u795e\u8d2f\u6ce8)\uff0c\u8868\u793a\u4ed6\u5e0c\u671b\u6e05\u695a\u5730\u4e86\u89e3\u81ea\u5df1\uff0c\u5fc5\u987b\u628a\u6240\u6709\u7684\u601d\u7eea\u96c6\u4e2d\u5230\u67d0\u4e2a\u70b9\u4e0a\u3002<\/p>\n<p>\u53d8\u5f62\u548c\u91cd\u751f\u53ea\u80fd\u901a\u8fc7\u5b8c\u5168\u6d78\u5165\u7cbe\u795e\u4e16\u754c\u624d\u80fd\u5b8c\u6210\u3002<\/p>\n<p>\u4ee5\u4e0a\u5c31\u662f\u7531\u6613\u5e08\u6c47\u89e3\u68a6\u680f\u76ee\u5c0f\u7f16\u5e2e\u4f60\u6574\u7406\u7684\u5173\u4e8e\u5468\u516c\u89e3\u68a6\u68a6\u89c1\u6d78\u5728\u6c34\u4e2d\u662f\u4ec0\u4e48\u5f81\u5146\uff1f\u68a6\u5230\u6d78\u5728\u6c34\u4e2d\u662f\u4ec0\u4e48\u5bd3\u610f\uff1f\u597d\u4e0d\u597d\u65b9\u9762\u7684\u5185\u5bb9\u3002\u5e0c\u671b\u5bf9\u5927\u5bb6\u6709\u6240\u5e2e\u52a9\u3002\u66f4\u591a\u89e3\u68a6\u53ef\u4ee5\u7ad9\u5185\u641c\u7d22\u5173\u952e\u8bcd\u5373\u53ef\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u68a6\u91cc\u68a6\u5230\u6d78\u5728\u6c34\u4e2d\u662f\u4ec0\u4e48\u5f81\u5146\uff1f\u5468\u516c\u89e3\u68a6\u68a6\u89c1\u6d78\u5728\u6c34\u4e2d\u662f\u4ec0\u4e48\u610f\u601d\uff1f\u68a6\u5230\u6d78\u5728\u6c34\u4e2d\u9884\u793a\u7740\u4ec0\u4e48\uff1f\u597d\u4e0d\u597d\uff1f\u505a\u68a6\u68a6\u89c1\u6d78\u5728\u6c34\u4e2d\u6709\u4ec0\u4e48\u5bd3\u610f?\u5f88\u591a\u4eba\u90fd\u6709\u8fd9\u65b9\u9762\u7684\u89e3\u68a6\u7591\u8651\u3002\u4eca\u5929\u6613\u5e08\u6c47\u89e3\u68a6\u680f\u76ee\u5c0f\u7f16\u5e2e\u4f60\u6574\u7406\u7684\u68a6\u89c1\u6d78\u5728\u6c34\u4e2d\u7684\u8be6\u7ec6\u89e3\u8bf4\u3002 \u68a6\u89c1\u6d78\u5728\u6c34\u4e2d\u662f\u4ec0\u4e48\u5bd3\u610f\u5468\u516c\u89e3\u68a6\uff1f\u68a6\u89c1\u4fb5\u5728\u6c34\u4e2d\u597d\u4e0d\u597d\uff1f \u68a6\u5230\u81ea\u5df1\u88ab\u6d78\u5165\u6c34\u4e2d\uff0c\u4e00\u822c\u8868\u793a\u68a6\u8005\u5904\u7406\u611f\u60c5\u7684\u72b6\u51b5\u3002\u4ed6\u8bd5\u7740\u5bfb\u627e\u6027\u683c\u4e2d\u7edd\u4e0d\u80fd\u88ab\u5916\u754c\u73af\u5883\u5f71\u54cd\u7684\u65e0\u8f9c\u7684\u90e8\u5206\u3002\u4ed6&hellip; <a href=\"http:\/\/ms.yishihui.net\/meng\/5150.htm\" class=\"more-link read-more\" rel=\"bookmark\">\u7ee7\u7eed\u9605\u8bfb <span class=\"screen-reader-text\">\u68a6\u89c1\u6d78\u5728\u6c34\u4e2d\u4ec0\u4e48\u5bd3\u610f\u5468\u516c\u89e3\u68a6\uff1f\u68a6\u89c1\u4fb5\u5165\u6c34\u4e2d\u597d\u5417\uff1f<\/span><i class=\"fa fa-arrow-right\"><\/i><\/a><\/p>\n","protected":false},"author":1,"featured_media":6466,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2233],"tags":[22,30,11,37],"class_list":{"0":"post-5150","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-qtsh","8":"tag-22","9":"tag-30","10":"tag-11","11":"tag-37","12":"h-entry","14":"h-as-article"},"_links":{"self":[{"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/posts\/5150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/comments?post=5150"}],"version-history":[{"count":2,"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/posts\/5150\/revisions"}],"predecessor-version":[{"id":7715,"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/posts\/5150\/revisions\/7715"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/media\/6466"}],"wp:attachment":[{"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/media?parent=5150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/categories?post=5150"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ms.yishihui.net\/meng\/wp-json\/wp\/v2\/tags?post=5150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}